{"id":846,"date":"2022-05-23T17:27:26","date_gmt":"2022-05-23T17:27:26","guid":{"rendered":"https:\/\/web.tarleton.edu\/tlc\/?page_id=846"},"modified":"2026-01-13T17:27:13","modified_gmt":"2026-01-13T17:27:13","slug":"courses-tutored","status":"publish","type":"page","link":"https:\/\/www.tarleton.edu\/tlc\/tutoring\/courses-tutored\/","title":{"rendered":"Courses Tutored"},"content":{"rendered":"\n<div class=\"wp-block-advgb-columns advgb-columns-wrapper\" id=\"advgb-cols-8503321b-c54f-44ea-bc2d-aac331038936\"><div class=\"advgb-columns-container\"><div class=\"advgb-columns advgb-columns-row advgb-is-mobile advgb-columns-2 layout-23-13 mbl-layout-stacked gutter-30 vgutter-10 order-rtl\">\n<div class=\"wp-block-advgb-column advgb-column advgb-is-two-thirds-tablet advgb-is-full-mobile\" id=\"advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<h1 class=\"wp-block-heading\">Tarleton Tutoring<\/h1>\n\n\n\n<p>Location: Dick Smith Library &#8211;&nbsp;<a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/\">Stephenville<\/a>&nbsp;(and&nbsp;<a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/online-tutoring\/\">Online<\/a>)<\/p>\n\n\n\n<p>Location: CAB 225 &#8211;&nbsp;<a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/fort-worth-campus\/\">Fort Worth<\/a>&nbsp;(and&nbsp;<a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/online-tutoring\/\">Online<\/a>)<\/p>\n\n\n\n<p>The Tarleton Tutoring program in Stephenville along with the Fort Worth Achievement Center can assist students with their tutoring needs at all campus locations through online support.  Some in-person tutoring may be limited to a specific campus. Reach out to our TLC staff to discuss your options.<\/p>\n\n\n\n<p>To make an appointment: Contact the tutoring office by phone&nbsp;<a href=\"tel:+12549689293\">254-968-9293<\/a>&nbsp;or email&nbsp;<a href=\"mailto:tutoring@tarleton.edu\">tutoring@tarleton.edu<\/a>.<\/p>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-advgb-column advgb-column advgb-is-one-third-tablet advgb-is-full-mobile\" id=\"advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229\"><div class=\"advgb-column-inner\" style=\"border-style:none;border-width:1px\">\n<div class=\"wp-block-advgb-button alignfull\"><a class=\"wp-block-advgb-button_link advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f\" href=\"https:\/\/tarleton.az1.qualtrics.com\/jfe\/form\/SV_bOO7cPmGS8yvfEx\" target=\"_blank\" rel=\"noopener noreferrer\"><span>Survey<\/span><\/a><\/div>\n\n\n\n<div class=\"wp-block-group extra-padding has-white-color has-text-color has-background is-layout-flow wp-block-group-is-layout-flow\" style=\"background-color:#424242\">\n<h2 class=\"wp-block-heading has-white-color has-text-color\">Customer Satisfaction Survey<\/h2>\n\n\n\n<p>Did you receive tutoring? If so, please complete our customer satisfaction survey. Your feedback helps us to continuously improve our tutoring program!<\/p>\n<\/div>\n<\/div><\/div>\n<\/div><\/div><\/div>\n\n\n\n<div style=\"height:31px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Spring 2026<\/h2>\n\n\n\n<p class=\"caution has-texan-white-color has-text-color has-background\" style=\"background-color:#333333\">Courses updated 01\/12\/26<\/p>\n\n\n\n<p class=\"information has-texan-white-color has-tarleton-purple-background-color has-text-color has-background\">If you don&#8217;t see your course listed, let us know your interest in tutoring for that subject. Also, check out the <a href=\"https:\/\/www.tarleton.edu\/tlc\/si\/courses\/\">courses supported by SI<\/a>.<\/p>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\">Accounting<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ACCT 2301 Principles of Accounting I &#8211; Financial&nbsp;<\/li>\n\n\n\n<li>ACCT 2302 Principles of Accounting II &#8211; Managerial<\/li>\n<\/ul>\n\n\n\n<p>Additional 3000 and 4000 level accounting courses are tutored online and in-person on the Fort Worth campus through our&nbsp;<a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/fort-worth-campus\/\">Fort Worth Achievement Center<\/a>. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Animal Science<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ANSC 1319 General Animal Science<\/li>\n\n\n\n<li>ANSC 2450 A&amp;P of Domestic Animals<\/li>\n\n\n\n<li>ANSC 3308 Principles of Animal Nutrition<\/li>\n\n\n\n<li>ANSC 3408 Physiology of Reproduction<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Biology<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>BIOL 1406 Biology for Science Majors<\/li>\n\n\n\n<li>BIOL 1407 Biology for Science Majors II<\/li>\n\n\n\n<li>BIOL 2300 Cell Biology<\/li>\n\n\n\n<li>BIOL 2401 Anatomy &amp; Physiology I<\/li>\n\n\n\n<li>BIOL 2402 Anatomy &amp; Physiology II<\/li>\n\n\n\n<li>BIOL 3407 Microbiology for Science Majors<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Business <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>BUSI 2305 Business Statistics <\/li>\n<\/ul>\n\n\n\n<p>Additionally, BUSI 4359 Business Strategy and BUSI 5365 Managerial Statistics are tutored online and in-person on the Fort Worth campus through our&nbsp;<a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/fort-worth-campus\/\">Fort Worth Achievement Center<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Business Computer Information Systems<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>BCIS 1305 Business for Computer Applications<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Chemistry<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>CHEM 1302 Essentials of Elementary Chemistry<\/li>\n\n\n\n<li>CHEM 1311 College Chemistry I<\/li>\n\n\n\n<li>CHEM 1312 College Chemistry II<\/li>\n\n\n\n<li>CHEM 1407 Introductory Chemistry<\/li>\n\n\n\n<li>CHEM 1409 College Chemistry for Engineers<\/li>\n\n\n\n<li>CHEM 2323 Organic Chemistry I<\/li>\n\n\n\n<li>CHEM 2325 Organic Chemistry II<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Civil Engineering <\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>CVEN 2200 Surveying<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">College of Business Administration (online or in <a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/fort-worth-campus\/\" data-type=\"page\" data-id=\"887\">Fort Worth<\/a>)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>COBA 5101 Foundations of Accounting <\/li>\n\n\n\n<li>COBA 5102 Foundations of Finance&nbsp;<\/li>\n\n\n\n<li>COBA 5103 Foundations of Statistics&nbsp;<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Computer Science<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>COSC 1310 Procedural Programming<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Criminal Justice<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>CRIJ 1301 Introduction to Criminal Justice<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Economics<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ECON 2301 Principles of Macroeconomics<\/li>\n\n\n\n<li>ECON 2302 Principles of Microeconomics<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">English<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ENGL 1301 Composition I<\/li>\n\n\n\n<li>ENGL 1302 Composition II<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Engineering<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ENGR 1211 Fundamentals of Engineering I<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Finance (online or in <a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/fort-worth-campus\/\" data-type=\"page\" data-id=\"887\">Fort Worth<\/a>)<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>FINC 3301 Principles of Financial Management&nbsp;<\/li>\n\n\n\n<li>FINC 5307 Financial Management <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Geology<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>GEOL 1407 Intro to Environmental Science<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Government<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>GOVT 2305 Federal Government<\/li>\n\n\n\n<li>GOVT 2306 Texas Government<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">History<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>HIST 1301 United States History I<\/li>\n\n\n\n<li>HIST 1302 United States History II<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Mathematics<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>MATH 1314 College Algebra<\/li>\n\n\n\n<li>MATH 1316 Plane Trigonometry<\/li>\n\n\n\n<li>MATH 1324 Math for Business and Social Sciences I<\/li>\n\n\n\n<li>MATH 1325 Math for Business and Social Sciences II<\/li>\n\n\n\n<li>MATH 1342 Elementary Statistical Methods<\/li>\n\n\n\n<li>MATH 2412 Pre-Calculus<\/li>\n\n\n\n<li>MATH 2413 Calculus I<\/li>\n\n\n\n<li>MATH 2414 Calculus II (Online or in Fort Worth)<\/li>\n\n\n\n<li>MATH 3311 Probability &amp; Statistics I<\/li>\n\n\n\n<li>MATH 3320 Foundations of Math<\/li>\n\n\n\n<li>MATH 3433 Calculus III<\/li>\n\n\n\n<li>MATH 4305 Concepts of Elementary Math III<\/li>\n\n\n\n<li>MATH 4306 Partial Differential Equations<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Physics<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>PHYS 2425 University Physics I&nbsp;<\/li>\n\n\n\n<li>PHYS 2426 University Physics II<\/li>\n\n\n\n<li>PHYS 3334 Modern Physics I <\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Psychology<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>PSYC 2301 General Psychology<\/li>\n\n\n\n<li>PSYC 2317 Elementary Stats for Behavioral Sciences<\/li>\n\n\n\n<li>PSYC 3309 Writing in Psychology<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">University Studies<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>UNIV 0314 Foundations of College Algebra<\/li>\n\n\n\n<li>UNIV 0342 Foundations of Statistics<\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">Fort Worth Achievement Center (and online)<\/h2>\n\n\n\n<p>The Tarleton Tutoring Program offers tutoring services on the Fort Worth campus, <strong>located in CAB 225<\/strong>, and online to all Tarleton students at any campus location.<\/p>\n\n\n\n<p>Check out tutored courses and additional services available through the <a href=\"https:\/\/www.tarleton.edu\/tlc\/tutoring\/fort-worth-campus\/\">Fort Worth Achievement Center<\/a> <\/p>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity\"\/>\n\n\n\n<h2 class=\"wp-block-heading\">Additional Tutoring Services in Stephenville &amp; Online<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.tarleton.edu\/writing-center\/\" data-type=\"link\" data-id=\"https:\/\/www.tarleton.edu\/writing-center\/\">University Writing Center and Language Aides<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.tarleton.edu\/communications\/university-speaking-center\/\" target=\"_blank\" rel=\"noreferrer noopener\">Speaking Center<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.tarleton.edu\/cosm\/stem-achievement-centers\/math-clinic\/\" target=\"_blank\" rel=\"noreferrer noopener\">Math Achievement Center<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.tarleton.edu\/cosm\/stem-achievement-centers\/science-clinic\/\" target=\"_blank\" rel=\"noreferrer noopener\">Science Achievement Center<\/a><\/li>\n\n\n\n<li><a rel=\"noreferrer noopener\" href=\"https:\/\/www.tarleton.edu\/afe\/\" target=\"_blank\">Stephenville Accounting Lab<\/a>&nbsp;info and&nbsp;<a href=\"https:\/\/tarleton.sharepoint.com\/:w:\/s\/COBA-CollegeofBusinessAdministration\/EQR1mtIH6K9AtCJC0T0oTesBgoAeKEdE2x-57Sn_x0p9lA?e=ei9VA0\" target=\"_blank\" rel=\"noreferrer noopener\">schedule<\/a><\/li>\n<\/ul>\n\n\n\n<div style=\"height:15px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<style class=\"advgb-styles-renderer\">#advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2>.advgb-column-inner{}}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f{font-size:18px;color:#fff !important;background-color:#4f2d7f !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:0px !important;}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f > i {font-size:30px;color:inherit;float:left;margin-right:7px;}#advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229>.advgb-column-inner{}}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f{font-size:18px;color:#fff !important;background-color:#4f2d7f !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:0px !important;}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f > i {font-size:30px;color:inherit;float:left;margin-right:7px;}#advgb-cols-8503321b-c54f-44ea-bc2d-aac331038936{}@media screen and (max-width: 1023px) {#advgb-cols-8503321b-c54f-44ea-bc2d-aac331038936{}}@media screen and (max-width: 767px) {#advgb-cols-8503321b-c54f-44ea-bc2d-aac331038936{}}#advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-f9c398a2-996f-45b1-a8c2-5ed63dd978e2>.advgb-column-inner{}}#advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229>.advgb-column-inner{}@media screen and (max-width: 1023px) {#advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229>.advgb-column-inner{}}@media screen and (max-width: 767px) {#advgb-col-1b484c8b-63ff-40ce-b231-702cbc74d229>.advgb-column-inner{}}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f{font-size:18px;color:#fff !important;background-color:#4f2d7f !important;margin:0px 0px 0px 0px !important;padding:10px 30px 10px 30px;border-width:1px !important;border-style:none;border-radius:0px !important;}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f:hover{box-shadow:1px 1px 12px 0px #ccc;opacity:1;transition:all 0.2s ease;}.advgbbtn-b5591193-2806-4b91-91fc-d24d581f093f > i {font-size:30px;color:inherit;float:left;margin-right:7px;}<\/style>","protected":false},"excerpt":{"rendered":"<p>Spring 2026 Courses updated 01\/12\/26 If you don&#8217;t see your course listed, let us know your interest in tutoring for that subject. Also, check out the courses supported by SI. &#8230;<\/p>\n","protected":false},"author":62,"featured_media":580,"parent":832,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"template-fullwidth.php","meta":{"_acf_changed":false,"inline_featured_image":false,"advgb_blocks_editor_width":"","advgb_blocks_columns_visual_guide":"","footnotes":""},"class_list":["post-846","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"coauthors":[],"author_meta":{"author_link":"https:\/\/www.tarleton.edu\/tlc\/author\/kyle-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-2-3\/","display_name":"kyle"},"relative_dates":{"created":"Posted 4 years ago","modified":"Updated 4 months ago"},"absolute_dates":{"created":"Posted on May 23, 2022","modified":"Updated on January 13, 2026"},"absolute_dates_time":{"created":"Posted on May 23, 2022 5:27 pm","modified":"Updated on January 13, 2026 5:27 pm"},"featured_img_caption":"","featured_img":false,"series_order":"","_links":{"self":[{"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/pages\/846","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/users\/62"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/comments?post=846"}],"version-history":[{"count":16,"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/pages\/846\/revisions"}],"predecessor-version":[{"id":2590,"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/pages\/846\/revisions\/2590"}],"up":[{"embeddable":true,"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/pages\/832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.tarleton.edu\/tlc\/wp-json\/wp\/v2\/media?parent=846"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}